{"id":937,"date":"2020-03-03T11:43:32","date_gmt":"2020-03-03T10:43:32","guid":{"rendered":"https:\/\/allgrafics.de\/kunden\/denkmal\/agrob\/?page_id=937"},"modified":"2022-04-04T11:59:33","modified_gmt":"2022-04-04T09:59:33","slug":"fliesenproduktion-film","status":"publish","type":"page","link":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/fliesenproduktion-film\/","title":{"rendered":"Fliesenproduktion Film"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.14.8&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_menu menu_id=&#8220;2&#8243; _builder_version=&#8220;4.13.0&#8243; _module_preset=&#8220;default&#8220; menu_font_size=&#8220;18px&#8220; global_colors_info=&#8220;{}&#8220; global_module=&#8220;4387&#8243; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_fullwidth_menu][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.0.9&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.0.9&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.0.9&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.0.9&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Sehen Sie hier den Film \u00fcber die Fliesenproduktion in Schablonentechnik mit 3D-Animationen.<\/h3>\n<p>[\/et_pb_text][et_pb_video src=&#8220;https:\/\/www.youtube.com\/watch?v=pWBK4rkQ0PA&#8220; image_src=&#8220;https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-content\/uploads\/2020\/03\/thump.jpg&#8220; thumbnail_overlay_color=&#8220;rgba(0,0,0,0.6)&#8220; _builder_version=&#8220;4.0.9&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sehen Sie hier den Film \u00fcber die Fliesenproduktion in Schablonentechnik mit 3D-Animationen.<\/p>\n","protected":false},"author":1,"featured_media":939,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"_links":{"self":[{"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/pages\/937"}],"collection":[{"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/comments?post=937"}],"version-history":[{"count":32,"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/pages\/937\/revisions"}],"predecessor-version":[{"id":4864,"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/pages\/937\/revisions\/4864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/media\/939"}],"wp:attachment":[{"href":"https:\/\/www.museumsinzig.de\/stadtgeschichte\/wp-json\/wp\/v2\/media?parent=937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}